{"id":18979,"date":"2026-03-24T15:44:13","date_gmt":"2026-03-24T18:44:13","guid":{"rendered":"https:\/\/www.cambe.pr.gov.br\/?p=18979"},"modified":"2026-03-24T15:44:13","modified_gmt":"2026-03-24T18:44:13","slug":"cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26","status":"publish","type":"post","link":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/","title":{"rendered":"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26)"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400; font-family: arial, helvetica, sans-serif;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-large wp-image-18980\" src=\"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-1024x678.jpg\" alt=\"\" width=\"610\" height=\"404\" srcset=\"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-1024x678.jpg 1024w, https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-300x199.jpg 300w, https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-768x509.jpg 768w, https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-1536x1017.jpg 1536w, https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-2048x1356.jpg 2048w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/>Um espet\u00e1culo de f\u00e9 e reflex\u00e3o. Camb\u00e9 recebe mais uma vez a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26). O teatro acontece no per\u00edodo entre a condena\u00e7\u00e3o, caminho at\u00e9 a cruz, morte e ressurrei\u00e7\u00e3o de Jesus Cristo, iniciando as celebra\u00e7\u00f5es de P\u00e1scoa. O evento \u00e9 gratuito e acontece no Parque Zez\u00e3o a partir das 20h. A Paix\u00e3o de Cristo conta com o apoio da Prefeitura por meio da Secretaria Municipal de Educa\u00e7\u00e3o e Cultura.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400; font-family: arial, helvetica, sans-serif;\">Em 2025, Camb\u00e9 recebeu o espet\u00e1culo pela primeira vez, emocionando milhares de fi\u00e9is que lotaram o Zez\u00e3o. O espet\u00e1culo contou com uma estrutura de aproximadamente 140 atores, divididos entre 26 cenas e uma dura\u00e7\u00e3o de 1h40. Ao todo, foram quatro estruturas de cen\u00e1rios, baseados nas descri\u00e7\u00f5es do historiador judaico-romano Fl\u00e1vio Josefo, como a Fortaleza Ant\u00f4nia, sede de Pilatos, com quatro torres e estilo de arquitetura rom\u00e2nica, e o Sin\u00e9drio, ou Templo de Salom\u00e3o. Al\u00e9m disso, pensando na seguran\u00e7a de todos, o evento contou com equipes de seguran\u00e7a; uma ambul\u00e2ncia para atender quem precisasse, por meio da Secretaria de Sa\u00fade P\u00fablica; ruas monitoradas pelos agentes de tr\u00e2nsito da Secretaria Municipal de Seguran\u00e7a P\u00fablica e Tr\u00e2nsito; e apoio da Pol\u00edcia Militar e Corpo de Bombeiros.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400; font-family: arial, helvetica, sans-serif;\">Para este ano, a expectativa da secret\u00e1ria municipal de Educa\u00e7\u00e3o e Cultura, Estela Camata, \u00e9 de um evento ainda mais emocionante e que impacte as pessoas durante o per\u00edodo sagrado para os crist\u00e3os. \u201cEstamos vivendo esse momento de prepara\u00e7\u00e3o, de muita f\u00e9, que \u00e9 a quaresma para n\u00f3s cat\u00f3licos. E acredito que o tema \u00e9 carregado de enorme sensibilidade. Trazer a apresenta\u00e7\u00e3o da Paix\u00e3o de Cristo para Camb\u00e9 era um sonho h\u00e1 muito tempo. Ano passado tivemos pela primeira vez e o p\u00fablico gostou muito. E esse ano a expectativa novamente \u00e9 de momentos de reflex\u00e3o, emo\u00e7\u00e3o, f\u00e9, mergulhar nesse momento em que a nossa religi\u00e3o, aquilo que a gente acredita, faz com que a gente possa se entender melhor como ser humano. Esperamos todos os cambeenses para esse momento especial, junto com a Secretaria de Cultura e da Prefeitura. Vamos juntos celebrar esse teatro que \u00e9 \u00fanico\u201d, destacou.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um espet\u00e1culo de f\u00e9 e reflex\u00e3o. Camb\u00e9 recebe mais uma vez a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26). O teatro acontece no per\u00edodo entre a condena\u00e7\u00e3o, caminho at\u00e9 a cruz, morte e ressurrei\u00e7\u00e3o de Jesus Cristo, iniciando as celebra\u00e7\u00f5es de P\u00e1scoa. O evento \u00e9 gratuito e acontece no Parque Zez\u00e3o a partir das [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18979","post","type-post","status-publish","format-standard","hentry","category-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26) - Prefeitura de Camb\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26) - Prefeitura de Camb\u00e9\" \/>\n<meta property=\"og:description\" content=\"Um espet\u00e1culo de f\u00e9 e reflex\u00e3o. Camb\u00e9 recebe mais uma vez a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26). O teatro acontece no per\u00edodo entre a condena\u00e7\u00e3o, caminho at\u00e9 a cruz, morte e ressurrei\u00e7\u00e3o de Jesus Cristo, iniciando as celebra\u00e7\u00f5es de P\u00e1scoa. O evento \u00e9 gratuito e acontece no Parque Zez\u00e3o a partir das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura de Camb\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/prefeituradecambe\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T18:44:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1695\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vinicius Augusto Batista Eira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vinicius Augusto Batista Eira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/\"},\"author\":{\"name\":\"Vinicius Augusto Batista Eira\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#\\\/schema\\\/person\\\/8e3ee69cb2cadf4b9f8377407227effd\"},\"headline\":\"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26)\",\"datePublished\":\"2026-03-24T18:44:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/\"},\"wordCount\":397,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC_0423-Aprimorado-NR-1024x678.jpg\",\"articleSection\":[\"Principal\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/\",\"name\":\"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26) - Prefeitura de Camb\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC_0423-Aprimorado-NR-1024x678.jpg\",\"datePublished\":\"2026-03-24T18:44:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC_0423-Aprimorado-NR-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC_0423-Aprimorado-NR-scaled.jpg\",\"width\":2560,\"height\":1695},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/\",\"name\":\"Prefeitura de Camb\u00e9\",\"description\":\"UM GOVERNO PARA TODOS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#organization\",\"name\":\"Prefeitura de Camb\u00e9\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-cropped-cambe_brazao-icone.png\",\"contentUrl\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-cropped-cambe_brazao-icone.png\",\"width\":240,\"height\":240,\"caption\":\"Prefeitura de Camb\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/prefeituradecambe\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#\\\/schema\\\/person\\\/8e3ee69cb2cadf4b9f8377407227effd\",\"name\":\"Vinicius Augusto Batista Eira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g\",\"caption\":\"Vinicius Augusto Batista Eira\"},\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/author\\\/vabeira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26) - Prefeitura de Camb\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/","og_locale":"pt_BR","og_type":"article","og_title":"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26) - Prefeitura de Camb\u00e9","og_description":"Um espet\u00e1culo de f\u00e9 e reflex\u00e3o. Camb\u00e9 recebe mais uma vez a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26). O teatro acontece no per\u00edodo entre a condena\u00e7\u00e3o, caminho at\u00e9 a cruz, morte e ressurrei\u00e7\u00e3o de Jesus Cristo, iniciando as celebra\u00e7\u00f5es de P\u00e1scoa. O evento \u00e9 gratuito e acontece no Parque Zez\u00e3o a partir das [&hellip;]","og_url":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/","og_site_name":"Prefeitura de Camb\u00e9","article_publisher":"https:\/\/m.facebook.com\/prefeituradecambe","article_published_time":"2026-03-24T18:44:13+00:00","og_image":[{"width":2560,"height":1695,"url":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-scaled.jpg","type":"image\/jpeg"}],"author":"Vinicius Augusto Batista Eira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vinicius Augusto Batista Eira","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/#article","isPartOf":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/"},"author":{"name":"Vinicius Augusto Batista Eira","@id":"https:\/\/www.cambe.pr.gov.br\/#\/schema\/person\/8e3ee69cb2cadf4b9f8377407227effd"},"headline":"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26)","datePublished":"2026-03-24T18:44:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/"},"wordCount":397,"publisher":{"@id":"https:\/\/www.cambe.pr.gov.br\/#organization"},"image":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-1024x678.jpg","articleSection":["Principal"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/","url":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/","name":"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26) - Prefeitura de Camb\u00e9","isPartOf":{"@id":"https:\/\/www.cambe.pr.gov.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/#primaryimage"},"image":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-1024x678.jpg","datePublished":"2026-03-24T18:44:13+00:00","breadcrumb":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/#primaryimage","url":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-scaled.jpg","contentUrl":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/DSC_0423-Aprimorado-NR-scaled.jpg","width":2560,"height":1695},{"@type":"BreadcrumbList","@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/cambe-recebe-a-encenacao-a-paixao-de-cristo-nesta-quinta-feira-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cambe.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"Camb\u00e9 recebe a encena\u00e7\u00e3o \u201cA Paix\u00e3o de Cristo\u201d nesta quinta-feira (26)"}]},{"@type":"WebSite","@id":"https:\/\/www.cambe.pr.gov.br\/#website","url":"https:\/\/www.cambe.pr.gov.br\/","name":"Prefeitura de Camb\u00e9","description":"UM GOVERNO PARA TODOS","publisher":{"@id":"https:\/\/www.cambe.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cambe.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cambe.pr.gov.br\/#organization","name":"Prefeitura de Camb\u00e9","url":"https:\/\/www.cambe.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cambe.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2021\/01\/cropped-cropped-cambe_brazao-icone.png","contentUrl":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2021\/01\/cropped-cropped-cambe_brazao-icone.png","width":240,"height":240,"caption":"Prefeitura de Camb\u00e9"},"image":{"@id":"https:\/\/www.cambe.pr.gov.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/prefeituradecambe"]},{"@type":"Person","@id":"https:\/\/www.cambe.pr.gov.br\/#\/schema\/person\/8e3ee69cb2cadf4b9f8377407227effd","name":"Vinicius Augusto Batista Eira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g","caption":"Vinicius Augusto Batista Eira"},"url":"https:\/\/www.cambe.pr.gov.br\/index.php\/author\/vabeira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/18979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=18979"}],"version-history":[{"count":1,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/18979\/revisions"}],"predecessor-version":[{"id":18981,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/18979\/revisions\/18981"}],"wp:attachment":[{"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=18979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=18979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=18979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}