{"id":18915,"date":"2026-03-18T14:36:07","date_gmt":"2026-03-18T17:36:07","guid":{"rendered":"https:\/\/www.cambe.pr.gov.br\/?p=18915"},"modified":"2026-03-18T14:36:07","modified_gmt":"2026-03-18T17:36:07","slug":"prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua","status":"publish","type":"post","link":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/","title":{"rendered":"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-18917 size-large\" src=\"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador-1024x683.jpg\" alt=\"\" width=\"610\" height=\"407\" srcset=\"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador-1024x683.jpg 1024w, https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador-300x200.jpg 300w, https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador-768x512.jpg 768w, https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador.jpg 1099w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/>Refor\u00e7ando o acolhimento com dignidade e ampliando estrat\u00e9gias para implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas, a Prefeitura de Camb\u00e9 preparou uma s\u00e9rie de a\u00e7\u00f5es para a popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua na pr\u00f3xima semana. A Secretaria Municipal de Assist\u00eancia Social e Cidadania organizou duas frentes de trabalho para atender essa popula\u00e7\u00e3o, com um censo para mapear a situa\u00e7\u00e3o e planejar de forma adequada tudo que ser\u00e1 feito posteriormente; e um mutir\u00e3o com v\u00e1rias frentes de atendimento municipal para garantir mais oportunidades e encaminhamentos para reinser\u00e7\u00e3o social.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Dos dias 23 a 25, de segunda a quarta-feira da pr\u00f3xima semana, ser\u00e1 realizado o Censo da Popula\u00e7\u00e3o em Situa\u00e7\u00e3o de Rua. O objetivo aqui \u00e9 mapear a situa\u00e7\u00e3o de momento, conhecer o perfil dessas pessoas, identificar, quantificar e levantar necessidades e demandas. Segundo a Secretaria, a a\u00e7\u00e3o \u00e9 fundamental para conhecer realmente essa popula\u00e7\u00e3o e, s\u00f3 assim, planejar, aprimorar e implementar as pol\u00edticas p\u00fablicas posteriormente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">E, como parte das estrat\u00e9gias de atendimento, levantamento desses dados e garantia de acesso aos servi\u00e7os p\u00fablicos, tamb\u00e9m ser\u00e1 feito um mutir\u00e3o intersetorial com a participa\u00e7\u00e3o de diversas secretarias e pol\u00edticas p\u00fablicas. Participam do mutir\u00e3o as secretarias de Assist\u00eancia Social, Comunica\u00e7\u00e3o, Sa\u00fade, Educa\u00e7\u00e3o, Trabalho e Meio Ambiente; e tamb\u00e9m o Conselho da Comunidade, Defensoria P\u00fablica e Instituto de Identifica\u00e7\u00e3o. O mutir\u00e3o ser\u00e1 na segunda-feira (23), a partir das 9h, na Rua Fortaleza, 520.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Censo da popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A secret\u00e1ria municipal de Assist\u00eancia Social e Cidadania, Fl\u00e1via Iwakura, explica que foi pensada uma estrat\u00e9gia que propicie um atendimento digno e de qualidade para essa popula\u00e7\u00e3o, e que, ao mesmo tempo, se consiga identificar e registrar quem s\u00e3o eles. Apesar dos dados j\u00e1 levantados, registros de atendimento e base de dados do Cad\u00danico, muitos n\u00fameros divergem e n\u00e3o coincidem. Segundo a secret\u00e1ria, esse \u00e9 um problema que vem sendo observado em todo o estado, e a a\u00e7\u00e3o \u00e9 uma iniciativa da Secretaria de Estado de Justi\u00e7a.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A partir desse problema, na pr\u00f3xima semana ser\u00e1 feita uma busca ativa desses moradores de rua, mesmo os que n\u00e3o comparecerem no mutir\u00e3o de servi\u00e7os, para o preenchimento de um formul\u00e1rio desenvolvido em parceria com o Instituto Paranaense de Desenvolvimento Econ\u00f4mico e Social (Ipardes). A mesma base de dados ser\u00e1 usada nos seis munic\u00edpios da regi\u00e3o (Camb\u00e9, Londrina, Ibipor\u00e3, Rol\u00e2ndia, Arapongas e Apucarana), j\u00e1 que muitos dos moradores s\u00e3o trecheiros, cruzando as informa\u00e7\u00f5es e identificando cada um deles para ter um levantamento o mais fidedigno poss\u00edvel.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201cHoje isso \u00e9 uma grande preocupa\u00e7\u00e3o nossa. Precisamos coletar esses dados, levantar o perfil e obter o n\u00famero mais real poss\u00edvel. N\u00e3o existe uma pol\u00edtica p\u00fablica efetiva sem um diagn\u00f3stico da quest\u00e3o colocada em pauta. Portanto, para coletar os dados necess\u00e1rios para o planejamento das a\u00e7\u00f5es, vamos lan\u00e7ar esse mutir\u00e3o de servi\u00e7os em uma estrat\u00e9gia de acolhida, com dignidade e cuidado para essas pessoas, e suprindo essa nossa demanda\u201d, destacou a secret\u00e1ria.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Servi\u00e7os oferecidos para a popula\u00e7\u00e3o<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua atendida no mutir\u00e3o ter\u00e1 acesso a diversos servi\u00e7os p\u00fablicos municipais. Na sa\u00fade, ter\u00e3o dispon\u00edvel: medi\u00e7\u00e3o da press\u00e3o arterial e glicemia; avalia\u00e7\u00e3o de peso, altura e c\u00e1lculo de \u00edndice de massa corp\u00f3rea (IMC); realiza\u00e7\u00e3o de testagem de HIV, hepatite e s\u00edfilis; vacina\u00e7\u00e3o de hepatite e t\u00e9tano; atendimento espec\u00edfico \u00e0 sa\u00fade da mulher para encaminhamentos e orienta\u00e7\u00f5es do preventivo, c\u00e2ncer de mama e \u00fatero, planejamento familiar e m\u00e9todos contraceptivos; avalia\u00e7\u00e3o e disponibiliza\u00e7\u00e3o de servi\u00e7os odontol\u00f3gicos em sa\u00fade bucal; classifica\u00e7\u00e3o de risco em sa\u00fade mental com encaminhamento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Na educa\u00e7\u00e3o, ser\u00e3o disponibilizadas informa\u00e7\u00f5es e oferta no EJA (Educa\u00e7\u00e3o de Jovens e Adultos); e tamb\u00e9m orienta\u00e7\u00f5es sobre documenta\u00e7\u00e3o escolar e encaminhamentos para matr\u00edcula.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Buscando uma transforma\u00e7\u00e3o de vida, a Secretaria de Trabalho vai orientar preenchimentos de curr\u00edculos; cadastramento e encaminhamento para vagas de emprego; e orienta\u00e7\u00f5es, cadastro em programas de curso e capacita\u00e7\u00f5es em prepara\u00e7\u00e3o para o mercado de trabalho. J\u00e1 o Instituto de Identifica\u00e7\u00e3o, que tamb\u00e9m fica na Ag\u00eancia do Trabalhador, estar\u00e1 orientando e encaminhando para a emiss\u00e3o de documentos pessoais, como a Carteira de Identifica\u00e7\u00e3o Nacional.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Como muitos desses moradores tamb\u00e9m t\u00eam animais, a Secretaria de Agricultura e Meio Ambiente estar\u00e1 fazendo orienta\u00e7\u00f5es sobre o bem-estar dos pets.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A Secretaria de Assist\u00eancia Social far\u00e1 a orienta\u00e7\u00e3o e informa\u00e7\u00e3o sobre o Cadastro \u00danico, benef\u00edcios e encaminhamentos; al\u00e9m dos servi\u00e7os essenciais e de cuidados ofertados pelo Abrigo Padre Manoel Coelho; e o preenchimento do Censo da Popula\u00e7\u00e3o de Rua.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">J\u00e1 o Conselho da Comunidade prestar\u00e1 orienta\u00e7\u00f5es jur\u00eddicas aos egressos de sistema prisional ou \u00e0queles que est\u00e3o em liberdade condicional.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Vale destacar que a Prefeitura segue com a a\u00e7\u00e3o contra a esmola para moradores em situa\u00e7\u00e3o de rua &#8211; <a href=\"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-de-cambe-lanca-campanha-de-conscientizacao-contra-esmola-para-populacao-em-situacao-de-rua\/\" target=\"_blank\" rel=\"noopener\"><strong>clique aqui e entenda melhor<\/strong><\/a>. Ao ver uma pessoa na rua, acione o servi\u00e7o de abordagem social pelo telefone <strong>(43) 99189-8789<\/strong>, que a Secretaria de Assist\u00eancia Social vai verificar a situa\u00e7\u00e3o e garantir o melhor encaminhamento para cada caso.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Refor\u00e7ando o acolhimento com dignidade e ampliando estrat\u00e9gias para implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas, a Prefeitura de Camb\u00e9 preparou uma s\u00e9rie de a\u00e7\u00f5es para a popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua na pr\u00f3xima semana. A Secretaria Municipal de Assist\u00eancia Social e Cidadania organizou duas frentes de trabalho para atender essa popula\u00e7\u00e3o, com um censo para mapear a [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18915","post","type-post","status-publish","format-standard","hentry","category-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua - Prefeitura de Camb\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua - Prefeitura de Camb\u00e9\" \/>\n<meta property=\"og:description\" content=\"Refor\u00e7ando o acolhimento com dignidade e ampliando estrat\u00e9gias para implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas, a Prefeitura de Camb\u00e9 preparou uma s\u00e9rie de a\u00e7\u00f5es para a popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua na pr\u00f3xima semana. A Secretaria Municipal de Assist\u00eancia Social e Cidadania organizou duas frentes de trabalho para atender essa popula\u00e7\u00e3o, com um censo para mapear a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura de Camb\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/prefeituradecambe\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-18T17:36:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1099\" \/>\n\t<meta property=\"og:image:height\" content=\"733\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vinicius Augusto Batista Eira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vinicius Augusto Batista Eira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/\"},\"author\":{\"name\":\"Vinicius Augusto Batista Eira\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#\\\/schema\\\/person\\\/8e3ee69cb2cadf4b9f8377407227effd\"},\"headline\":\"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua\",\"datePublished\":\"2026-03-18T17:36:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/\"},\"wordCount\":955,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/morador-1024x683.jpg\",\"articleSection\":[\"Principal\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/\",\"name\":\"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua - Prefeitura de Camb\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/morador-1024x683.jpg\",\"datePublished\":\"2026-03-18T17:36:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/morador.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/morador.jpg\",\"width\":1099,\"height\":733},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/\",\"name\":\"Prefeitura de Camb\u00e9\",\"description\":\"UM GOVERNO PARA TODOS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#organization\",\"name\":\"Prefeitura de Camb\u00e9\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-cropped-cambe_brazao-icone.png\",\"contentUrl\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-cropped-cambe_brazao-icone.png\",\"width\":240,\"height\":240,\"caption\":\"Prefeitura de Camb\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/prefeituradecambe\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/#\\\/schema\\\/person\\\/8e3ee69cb2cadf4b9f8377407227effd\",\"name\":\"Vinicius Augusto Batista Eira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g\",\"caption\":\"Vinicius Augusto Batista Eira\"},\"url\":\"https:\\\/\\\/www.cambe.pr.gov.br\\\/index.php\\\/author\\\/vabeira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua - Prefeitura de Camb\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua - Prefeitura de Camb\u00e9","og_description":"Refor\u00e7ando o acolhimento com dignidade e ampliando estrat\u00e9gias para implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas, a Prefeitura de Camb\u00e9 preparou uma s\u00e9rie de a\u00e7\u00f5es para a popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua na pr\u00f3xima semana. A Secretaria Municipal de Assist\u00eancia Social e Cidadania organizou duas frentes de trabalho para atender essa popula\u00e7\u00e3o, com um censo para mapear a [&hellip;]","og_url":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/","og_site_name":"Prefeitura de Camb\u00e9","article_publisher":"https:\/\/m.facebook.com\/prefeituradecambe","article_published_time":"2026-03-18T17:36:07+00:00","og_image":[{"width":1099,"height":733,"url":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador.jpg","type":"image\/jpeg"}],"author":"Vinicius Augusto Batista Eira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vinicius Augusto Batista Eira","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/#article","isPartOf":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/"},"author":{"name":"Vinicius Augusto Batista Eira","@id":"https:\/\/www.cambe.pr.gov.br\/#\/schema\/person\/8e3ee69cb2cadf4b9f8377407227effd"},"headline":"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua","datePublished":"2026-03-18T17:36:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/"},"wordCount":955,"publisher":{"@id":"https:\/\/www.cambe.pr.gov.br\/#organization"},"image":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador-1024x683.jpg","articleSection":["Principal"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/","url":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/","name":"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua - Prefeitura de Camb\u00e9","isPartOf":{"@id":"https:\/\/www.cambe.pr.gov.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/#primaryimage"},"image":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador-1024x683.jpg","datePublished":"2026-03-18T17:36:07+00:00","breadcrumb":{"@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/#primaryimage","url":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador.jpg","contentUrl":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2026\/03\/morador.jpg","width":1099,"height":733},{"@type":"BreadcrumbList","@id":"https:\/\/www.cambe.pr.gov.br\/index.php\/prefeitura-promove-mutirao-de-servicos-e-censo-para-populacao-em-situacao-de-rua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cambe.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"Prefeitura promove mutir\u00e3o de servi\u00e7os e censo para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua"}]},{"@type":"WebSite","@id":"https:\/\/www.cambe.pr.gov.br\/#website","url":"https:\/\/www.cambe.pr.gov.br\/","name":"Prefeitura de Camb\u00e9","description":"UM GOVERNO PARA TODOS","publisher":{"@id":"https:\/\/www.cambe.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cambe.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cambe.pr.gov.br\/#organization","name":"Prefeitura de Camb\u00e9","url":"https:\/\/www.cambe.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cambe.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2021\/01\/cropped-cropped-cambe_brazao-icone.png","contentUrl":"https:\/\/www.cambe.pr.gov.br\/wp-content\/uploads\/2021\/01\/cropped-cropped-cambe_brazao-icone.png","width":240,"height":240,"caption":"Prefeitura de Camb\u00e9"},"image":{"@id":"https:\/\/www.cambe.pr.gov.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/prefeituradecambe"]},{"@type":"Person","@id":"https:\/\/www.cambe.pr.gov.br\/#\/schema\/person\/8e3ee69cb2cadf4b9f8377407227effd","name":"Vinicius Augusto Batista Eira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ec500de7013b30e1d4d7c8c3978f0e4433c37e5d5e4cd186239369c6440122b?s=96&d=mm&r=g","caption":"Vinicius Augusto Batista Eira"},"url":"https:\/\/www.cambe.pr.gov.br\/index.php\/author\/vabeira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/18915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=18915"}],"version-history":[{"count":2,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/18915\/revisions"}],"predecessor-version":[{"id":18918,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/18915\/revisions\/18918"}],"wp:attachment":[{"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=18915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=18915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=18915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}